{"id":5134,"date":"2024-10-01T10:15:47","date_gmt":"2024-10-01T13:15:47","guid":{"rendered":"https:\/\/lavozdisruptiva.com\/?p=5134"},"modified":"2024-10-01T10:15:48","modified_gmt":"2024-10-01T13:15:48","slug":"desregulacion-milei-disolvio-el-instituto-argentino-del-transporte-iat-creado-por-cristina-kirchner-y-florencio-randazzo","status":"publish","type":"post","link":"https:\/\/lavozdisruptiva.com\/index.php\/2024\/10\/01\/desregulacion-milei-disolvio-el-instituto-argentino-del-transporte-iat-creado-por-cristina-kirchner-y-florencio-randazzo\/","title":{"rendered":"Desregulaci\u00f3n: Milei disolvi\u00f3 el Instituto Argentino del Transporte (IAT) creado por Cristina Kirchner y Florencio Randazzo"},"content":{"rendered":"\n<h2 class=\"wp-block-heading has-medium-font-size\">En el Gobierno consideran que el organismo comenz\u00f3 a mostrar superposici\u00f3n de funciones con otras \u00e1reas de la administraci\u00f3n, como la Secretar\u00eda de Transporte y la Agencia Nacional de Seguridad Vial.<\/h2>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">El<strong>&nbsp;Instituto Argentino del Transporte<\/strong>&nbsp;(I.A.T.), creado en 2014 con la misi\u00f3n de asesorar en la planificaci\u00f3n estrat\u00e9gica del transporte en Argentina, fue&nbsp;<strong>oficialmente disuelto a trav\u00e9s del Decreto 870\/2024<\/strong>. Esta medida, seg\u00fan la argumentaci\u00f3n gubernamental, se enmarca en la estrategia para racionalizar el gasto p\u00fablico y eliminar duplicidades en la administraci\u00f3n estatal.<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">El I.A.T. fue creado mediante el Decreto N\u00ba 1004\/14 por la ex presidenta&nbsp;<strong>Cristina Kirchner<\/strong>&nbsp;y su ministro&nbsp;<strong>Florencio Randazzo<\/strong>&nbsp;con el objetivo de integrar los sectores p\u00fablico y privado en la planificaci\u00f3n del transporte, promover la investigaci\u00f3n en esta \u00e1rea y colaborar con el Ministerio del Interior y Transporte en la elaboraci\u00f3n de programas de mejora.<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">No obstante, a lo largo de los a\u00f1os, el Instituto comenz\u00f3 a mostrar superposici\u00f3n de funciones con otras \u00e1reas de la administraci\u00f3n, <strong>como la Secretar\u00eda de Transporte y la Agencia Nacional de Seguridad Vial<\/strong>, que ya lideraban la planificaci\u00f3n y ejecuci\u00f3n de pol\u00edticas relacionadas con el transporte en el pa\u00eds.<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">En abril de 2024,&nbsp;<strong>con la promulgaci\u00f3n del Decreto N\u00ba 318\/24, el I.A.T. fue transferido al \u00e1mbito de la Secretar\u00eda de Transporte bajo la \u00f3rbita del Ministerio de Econom\u00eda<\/strong>. Sin embargo, tras una evaluaci\u00f3n del Gobierno, se determin\u00f3 que muchas de sus funciones eran redundantes, lo que llev\u00f3 a la decisi\u00f3n final de disolver el organismo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\">Los motivos detr\u00e1s de la disoluci\u00f3n<\/h3>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">El decreto justifica la disoluci\u00f3n del I.A.T. en un contexto de optimizaci\u00f3n de los recursos p\u00fablicos. S<strong>eg\u00fan el documento, la existencia del Instituto no se consideraba necesaria, ya que sus tareas pod\u00edan ser asumidas por otras dependencias que ya estaban operando en el \u00e1mbito del transporte.<\/strong>&nbsp;Esta medida se alinea con el objetivo del Gobierno de reducir el gasto p\u00fablico, eliminando entidades cuya contribuci\u00f3n al inter\u00e9s general se considera marginal.<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">En el texto se menciona expl\u00edcitamente la necesidad de maximizar la eficiencia del gasto, asegurando que los recursos estatales se destinen a \u00e1reas prioritarias y a quienes m\u00e1s lo necesitan. Esto se inscribe en la estrategia m\u00e1s amplia de la Administraci\u00f3n actual, que ha implementado diversas acciones para equilibrar las cuentas p\u00fablicas y mejorar la transparencia del gasto.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\">\u00bfQu\u00e9 pasar\u00e1 con los recursos del I.A.T.?<\/h3>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">El Decreto 870\/2024 establece que la totalidad de los recursos materiales y financieros del I.A.T.&nbsp;<strong>ser\u00e1n transferidos a la Secretar\u00eda de Transporte, que asumir\u00e1 las funciones que antes desempe\u00f1aba el Instituto<\/strong>. De esta forma, el Gobierno busca evitar la duplicaci\u00f3n de funciones y mejorar la eficiencia administrativa dentro del sector del transporte.<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Adem\u00e1s,&nbsp;<strong>el decreto deroga el Decreto N\u00ba 1004\/14, que hab\u00eda establecido la creaci\u00f3n del Instituto, formalizando as\u00ed su cierre definitivo<\/strong>.<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">La disoluci\u00f3n del I.A.T. se enmarca en un proceso m\u00e1s amplio de reforma y reestructuraci\u00f3n del aparato estatal impulsado por el Gobierno.<strong>&nbsp;Este tipo de medidas buscan no solo reducir costos, sino tambi\u00e9n mejorar la coordinaci\u00f3n entre las distintas \u00e1reas gubernamentales y optimizar el uso de los recursos<\/strong>.<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Desde la Administraci\u00f3n, se ha se\u00f1alado en diversas ocasiones que una gesti\u00f3n eficiente de los recursos p\u00fablicos es fundamental para el crecimiento econ\u00f3mico del pa\u00eds.\u00a0<strong>Al concentrar las funciones del I.A.T. en otras \u00e1reas que ya tienen competencia en el transporte<\/strong>, el Ejecutivo asegura que no se est\u00e9n destinando recursos a organismos innecesarios, y que el sector del transporte, crucial para el desarrollo econ\u00f3mico, sea gestionado de manera m\u00e1s eficaz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:23px\"><strong>Sturzenegger: &#8220;Son organismos para inventar cargos&#8221;<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong><em>&#8220;Durante el kirchnerismo el Estado creci\u00f3 desmedidamente, proliferando las funciones superpuestas o in\u00fatiles, creadas para inventar cargos. La tarea de ordenamiento va a llevar alg\u00fan tiempo; el resultado ser\u00e1 un Estado m\u00e1s \u00fatil y menos costoso<\/em><\/strong>&#8220;, afirm\u00f3 el ministro de Desregulaci\u00f3n y Transformaci\u00f3n del Estado, Federico Sturzenegger.<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Fuente: NA\/ medios digitales<br>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el Gobierno consideran que el organismo comenz\u00f3 a mostrar superposici\u00f3n de funciones con otras \u00e1reas de la administraci\u00f3n, como la Secretar\u00eda de Transporte y la Agencia Nacional de Seguridad Vial. El&nbsp;Instituto Argentino del Transporte&nbsp;(I.A.T.), creado en 2014 con la misi\u00f3n de asesorar en la planificaci\u00f3n estrat\u00e9gica del transporte en Argentina, fue&nbsp;oficialmente disuelto a trav\u00e9s [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":5135,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,81,39],"tags":[146,66,514,856,412,40],"class_list":["post-5134","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","category-nacional","category-politica","tag-desregulacion","tag-economia","tag-federico-sturzenegger","tag-instituto-argentino-del-transporte","tag-javier-milei","tag-politica"],"blog_post_layout_featured_media_urls":{"thumbnail":["https:\/\/lavozdisruptiva.com\/wp-content\/uploads\/2024\/10\/Tren-2-150x150.jpeg",150,150,true],"full":["https:\/\/lavozdisruptiva.com\/wp-content\/uploads\/2024\/10\/Tren-2.jpeg",1200,675,false]},"categories_names":{"4":{"name":"Econom\u00eda","link":"https:\/\/lavozdisruptiva.com\/index.php\/category\/economia\/"},"81":{"name":"Nacional","link":"https:\/\/lavozdisruptiva.com\/index.php\/category\/nacional\/"},"39":{"name":"Pol\u00edtica","link":"https:\/\/lavozdisruptiva.com\/index.php\/category\/politica\/"}},"tags_names":{"146":{"name":"Desregulaci\u00f3n","link":"https:\/\/lavozdisruptiva.com\/index.php\/tag\/desregulacion\/"},"66":{"name":"Econom\u00eda","link":"https:\/\/lavozdisruptiva.com\/index.php\/tag\/economia\/"},"514":{"name":"Federico Sturzenegger","link":"https:\/\/lavozdisruptiva.com\/index.php\/tag\/federico-sturzenegger\/"},"856":{"name":"Instituto Argentino del Transporte","link":"https:\/\/lavozdisruptiva.com\/index.php\/tag\/instituto-argentino-del-transporte\/"},"412":{"name":"Javier Milei","link":"https:\/\/lavozdisruptiva.com\/index.php\/tag\/javier-milei\/"},"40":{"name":"Pol\u00edtica","link":"https:\/\/lavozdisruptiva.com\/index.php\/tag\/politica\/"}},"comments_number":"0","wpmagazine_modules_lite_featured_media_urls":{"thumbnail":["https:\/\/lavozdisruptiva.com\/wp-content\/uploads\/2024\/10\/Tren-2-150x150.jpeg",150,150,true],"cvmm-medium":["https:\/\/lavozdisruptiva.com\/wp-content\/uploads\/2024\/10\/Tren-2-300x300.jpeg",300,300,true],"cvmm-medium-plus":["https:\/\/lavozdisruptiva.com\/wp-content\/uploads\/2024\/10\/Tren-2-305x207.jpeg",305,207,true],"cvmm-portrait":["https:\/\/lavozdisruptiva.com\/wp-content\/uploads\/2024\/10\/Tren-2-400x600.jpeg",400,600,true],"cvmm-medium-square":["https:\/\/lavozdisruptiva.com\/wp-content\/uploads\/2024\/10\/Tren-2-600x600.jpeg",600,600,true],"cvmm-large":["https:\/\/lavozdisruptiva.com\/wp-content\/uploads\/2024\/10\/Tren-2-1024x675.jpeg",1024,675,true],"cvmm-small":["https:\/\/lavozdisruptiva.com\/wp-content\/uploads\/2024\/10\/Tren-2-130x95.jpeg",130,95,true],"full":["https:\/\/lavozdisruptiva.com\/wp-content\/uploads\/2024\/10\/Tren-2.jpeg",1200,675,false]},"_links":{"self":[{"href":"https:\/\/lavozdisruptiva.com\/index.php\/wp-json\/wp\/v2\/posts\/5134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lavozdisruptiva.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lavozdisruptiva.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lavozdisruptiva.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lavozdisruptiva.com\/index.php\/wp-json\/wp\/v2\/comments?post=5134"}],"version-history":[{"count":1,"href":"https:\/\/lavozdisruptiva.com\/index.php\/wp-json\/wp\/v2\/posts\/5134\/revisions"}],"predecessor-version":[{"id":5136,"href":"https:\/\/lavozdisruptiva.com\/index.php\/wp-json\/wp\/v2\/posts\/5134\/revisions\/5136"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lavozdisruptiva.com\/index.php\/wp-json\/wp\/v2\/media\/5135"}],"wp:attachment":[{"href":"https:\/\/lavozdisruptiva.com\/index.php\/wp-json\/wp\/v2\/media?parent=5134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lavozdisruptiva.com\/index.php\/wp-json\/wp\/v2\/categories?post=5134"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lavozdisruptiva.com\/index.php\/wp-json\/wp\/v2\/tags?post=5134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}