{"id":3272,"date":"2024-01-25T11:25:17","date_gmt":"2024-01-25T14:25:17","guid":{"rendered":"https:\/\/lavozdisruptiva.com\/?p=3272"},"modified":"2024-01-25T11:25:18","modified_gmt":"2024-01-25T14:25:18","slug":"autos-mas-baratos-ahora-solo-los-de-mas-de-28-millones-pagaran-el-impuesto-al-lujo","status":"publish","type":"post","link":"https:\/\/lavozdisruptiva.com\/index.php\/2024\/01\/25\/autos-mas-baratos-ahora-solo-los-de-mas-de-28-millones-pagaran-el-impuesto-al-lujo\/","title":{"rendered":"Autos mas baratos:                                                               Ahora s\u00f3lo los de m\u00e1s de $28 millones pagar\u00e1n el impuesto al &#8220;lujo&#8221;"},"content":{"rendered":"\n<h2 class=\"wp-block-heading has-medium-font-size\">Se public\u00f3 el decreto en el Bolet\u00edn Oficial, que establece cambios en el r\u00e9gimen de impuestos internos para los 0 km. La base imponible para la primera escala que hoy est\u00e1 en $10.364.800 pasa a $ 19.826.151 y pagar\u00e1 una al\u00edcuota de 20%, mientras que la segunda escala sube de $19.135.000 a $36,602.126, con una al\u00edcuota de 35%.                    Las ventas estaban frenadas a la espera de una definici\u00f3n oficial sobre esta cuesti\u00f3n.<\/h2>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img decoding=\"async\" src=\"https:\/\/media.ambito.com\/p\/1c6d4cbd5f665a97606730419d1d9b2b\/adjuntos\/239\/imagenes\/041\/229\/0041229012\/655x368\/smart\/autos-0kmjpg.jpg\" alt=\"De esta forma se destraba el mercado automotor que estaba a la espera desde comienzo de enero de este cambio y las automotrices comenzar\u00e1n a facturar veh\u00edculos a la red y se conocer\u00e1n listas de precios oficiales de cada marca.\" style=\"width:840px;height:auto\"\/><figcaption class=\"wp-element-caption\">De esta forma se destraba el mercado automotor que estaba a la espera desde comienzo de enero de este cambio y las automotrices comenzar\u00e1n a facturar veh\u00edculos a la red y se conocer\u00e1n listas de precios oficiales de cada marca.<\/figcaption><\/figure>\n\n\n\n<p class=\"has-medium-font-size\">El Gobierno public\u00f3 hoy en el&nbsp;<strong>Bolet\u00edn Oficial<\/strong>&nbsp;que introduce cambios en el&nbsp;<a href=\"https:\/\/www.ambito.com\/economia\/autos-gobierno-define-nuevos-cambios-elimpuesto-al-lujo-0km-n5925541\" target=\"_blank\" rel=\"noreferrer noopener\">r\u00e9gimen de&nbsp;<strong>Impuestos Internos para los autos 0km<\/strong>.<\/a><\/p>\n\n\n\n<p class=\"has-medium-font-size\">Seg\u00fan la norma,\u00a0<strong>la base imponible para la primera escala que hoy est\u00e1 en $10.364.800 pasa a $ 19.826.151 y pagar\u00e1 una al\u00edcuota de 20%, mientras que la segunda escala sube de $19.135.000 a $36,602.126, con una al\u00edcuota de 35%.<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\">De esta manera,\u00a0<strong>los autos comenzar\u00e1n a tributar ahora, en el primer caso, a partir de aproximadamente $28.200.000 de precio al p\u00fablico (hoy lo hacen desde los $14.700.000), en tanto para el segundo caso pagar\u00e1n desde los $63.000.000 (hoy pagan desde los $32.000.000)<\/strong>.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">De esta forma se destraba el mercado automotor que estaba a la espera desde comienzo de enero de este cambio y las automotrices comenzar\u00e1n a facturar veh\u00edculos a la red y se conocer\u00e1n listas de precios oficiales de cada marca.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">En la pr\u00e1ctica, una gran cantidad de modelos dejar\u00e1n de pagar lo que se conoce como impuesto al \u201clujo\u201d y habr\u00e1 una reacomodamiento de los precios que se empezar\u00e1 a conocer en las pr\u00f3ximas horas cuando cada empresa difunda sus nuevas listas.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Fuente: Diario \u00c1mbito<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se public\u00f3 el decreto en el Bolet\u00edn Oficial, que establece cambios en el r\u00e9gimen de impuestos internos para los 0 km. La base imponible para la primera escala que hoy est\u00e1 en $10.364.800 pasa a $ 19.826.151 y pagar\u00e1 una al\u00edcuota de 20%, mientras que la segunda escala sube de $19.135.000 a $36,602.126, con una [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3273,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,81,6],"tags":[66,486],"class_list":["post-3272","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","category-nacional","category-noticias","tag-economia","tag-impuestos-autos"],"blog_post_layout_featured_media_urls":{"thumbnail":["https:\/\/lavozdisruptiva.com\/wp-content\/uploads\/2024\/01\/Auto-lujo-150x150.webp",150,150,true],"full":["https:\/\/lavozdisruptiva.com\/wp-content\/uploads\/2024\/01\/Auto-lujo.webp",1200,675,false]},"categories_names":{"4":{"name":"Econom\u00eda","link":"https:\/\/lavozdisruptiva.com\/index.php\/category\/economia\/"},"81":{"name":"Nacional","link":"https:\/\/lavozdisruptiva.com\/index.php\/category\/nacional\/"},"6":{"name":"Noticias","link":"https:\/\/lavozdisruptiva.com\/index.php\/category\/noticias\/"}},"tags_names":{"66":{"name":"Econom\u00eda","link":"https:\/\/lavozdisruptiva.com\/index.php\/tag\/economia\/"},"486":{"name":"Impuestos autos","link":"https:\/\/lavozdisruptiva.com\/index.php\/tag\/impuestos-autos\/"}},"comments_number":"0","wpmagazine_modules_lite_featured_media_urls":{"thumbnail":["https:\/\/lavozdisruptiva.com\/wp-content\/uploads\/2024\/01\/Auto-lujo-150x150.webp",150,150,true],"cvmm-medium":["https:\/\/lavozdisruptiva.com\/wp-content\/uploads\/2024\/01\/Auto-lujo-300x300.webp",300,300,true],"cvmm-medium-plus":["https:\/\/lavozdisruptiva.com\/wp-content\/uploads\/2024\/01\/Auto-lujo-305x207.webp",305,207,true],"cvmm-portrait":["https:\/\/lavozdisruptiva.com\/wp-content\/uploads\/2024\/01\/Auto-lujo-400x600.webp",400,600,true],"cvmm-medium-square":["https:\/\/lavozdisruptiva.com\/wp-content\/uploads\/2024\/01\/Auto-lujo-600x600.webp",600,600,true],"cvmm-large":["https:\/\/lavozdisruptiva.com\/wp-content\/uploads\/2024\/01\/Auto-lujo-1024x675.webp",1024,675,true],"cvmm-small":["https:\/\/lavozdisruptiva.com\/wp-content\/uploads\/2024\/01\/Auto-lujo-130x95.webp",130,95,true],"full":["https:\/\/lavozdisruptiva.com\/wp-content\/uploads\/2024\/01\/Auto-lujo.webp",1200,675,false]},"_links":{"self":[{"href":"https:\/\/lavozdisruptiva.com\/index.php\/wp-json\/wp\/v2\/posts\/3272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lavozdisruptiva.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lavozdisruptiva.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lavozdisruptiva.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lavozdisruptiva.com\/index.php\/wp-json\/wp\/v2\/comments?post=3272"}],"version-history":[{"count":1,"href":"https:\/\/lavozdisruptiva.com\/index.php\/wp-json\/wp\/v2\/posts\/3272\/revisions"}],"predecessor-version":[{"id":3274,"href":"https:\/\/lavozdisruptiva.com\/index.php\/wp-json\/wp\/v2\/posts\/3272\/revisions\/3274"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lavozdisruptiva.com\/index.php\/wp-json\/wp\/v2\/media\/3273"}],"wp:attachment":[{"href":"https:\/\/lavozdisruptiva.com\/index.php\/wp-json\/wp\/v2\/media?parent=3272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lavozdisruptiva.com\/index.php\/wp-json\/wp\/v2\/categories?post=3272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lavozdisruptiva.com\/index.php\/wp-json\/wp\/v2\/tags?post=3272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}