{"id":2408,"date":"2023-11-02T11:10:49","date_gmt":"2023-11-02T14:10:49","guid":{"rendered":"https:\/\/lavozdisruptiva.com\/?p=2408"},"modified":"2023-11-28T08:54:15","modified_gmt":"2023-11-28T11:54:15","slug":"plan-platita-massa-y-el-anses-anunciaron-ampliacion-de-prestamos-para-trabajadores-jubilados-pensionados-y-pensiones-no-contributivas","status":"publish","type":"post","link":"https:\/\/lavozdisruptiva.com\/index.php\/2023\/11\/02\/plan-platita-massa-y-el-anses-anunciaron-ampliacion-de-prestamos-para-trabajadores-jubilados-pensionados-y-pensiones-no-contributivas\/","title":{"rendered":"Plan &#8220;platita&#8221;: Massa y el ANSES anunciaron ampliaci\u00f3n de pr\u00e9stamos para trabajadores, jubilados, pensionados y pensiones no contributivas."},"content":{"rendered":"\n<h2 class=\"wp-block-heading has-medium-font-size\">Las l\u00edneas de cr\u00e9ditos ANSES pasan de $400.000 a $600.000 para jubilados y pensionados, y hasta $1 mill\u00f3n para trabajadores en relaci\u00f3n de dependencia. Ser\u00e1 desde el pr\u00f3ximo lunes 6 de noviembre.<\/h2>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">El ministro de Econom\u00eda y candidato a presidente,<strong>&nbsp;<a href=\"https:\/\/www.ambito.com\/sergio-massa-a5123403\" target=\"_blank\" rel=\"noreferrer noopener\">Sergio Massa<\/a>,&nbsp;<\/strong>y la directora ejecutiva de ANSES,&nbsp;<strong>Fernanda Raverta,<\/strong>&nbsp;anunciaron este mi\u00e9rcoles un&nbsp;<strong>aumento en el monto que ofrecen los Cr\u00e9ditos ANSES de $400.000 a $600.000&nbsp;<\/strong>para&nbsp;<strong>jubilados, pensionados<\/strong>&nbsp;y&nbsp;<strong>hasta $1 mill\u00f3n para trabajadores en relaci\u00f3n de dependencia<\/strong>, desde el pr\u00f3ximo lunes 6 de noviembre.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" src=\"https:\/\/lavozdisruptiva.com\/wp-content\/uploads\/2023\/11\/Massa-y-Raverta-Jubilacion-Anticipada-1024x681.jpeg\" alt=\"\" class=\"wp-image-2403\" srcset=\"https:\/\/lavozdisruptiva.com\/wp-content\/uploads\/2023\/11\/Massa-y-Raverta-Jubilacion-Anticipada-1024x681.jpeg 1024w, https:\/\/lavozdisruptiva.com\/wp-content\/uploads\/2023\/11\/Massa-y-Raverta-Jubilacion-Anticipada-300x200.jpeg 300w, https:\/\/lavozdisruptiva.com\/wp-content\/uploads\/2023\/11\/Massa-y-Raverta-Jubilacion-Anticipada-768x511.jpeg 768w, https:\/\/lavozdisruptiva.com\/wp-content\/uploads\/2023\/11\/Massa-y-Raverta-Jubilacion-Anticipada-1536x1022.jpeg 1536w, https:\/\/lavozdisruptiva.com\/wp-content\/uploads\/2023\/11\/Massa-y-Raverta-Jubilacion-Anticipada-2048x1363.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">En este marco, Massa expres\u00f3:<strong>&nbsp;\u201cEst\u00e1 decisi\u00f3n mejora la capacidad de cr\u00e9dito de trabajadores y jubilados en la Argentina. Aspiramos, adem\u00e1s, a que esta medida sirva, en muchos casos, para resolver temas de endeudamiento, de tarjeta de cr\u00e9dito, de mutuales, que sabemos que a veces complican la vida del trabajador. Y para aquellos que no tienen deuda, sirva a los efectos de avanzar de manera bancarizada, de manera digital, con la compra de bienes o con la contrataci\u00f3n de aquellos servicios, ya sea para la familia o de turismo, que necesiten\u201d.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Cr\u00e9ditos para trabajadores, jubilados y pensionados<\/h2>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">En tanto, Raverta sostuvo:<strong>&nbsp;\u201cEl cr\u00e9dito a los trabajadores va a pasar de 400 mil a un mill\u00f3n de pesos, que va a devolverse en 24, 36 o 48 cuotas. Ese dinero se va a depositar en la tarjeta de cr\u00e9dito con el fin de ayudar a desendeudarse, pero tambi\u00e9n est\u00e1 orientado al consumo, sin extraerse de la tarjeta, con una tasa de inter\u00e9s del 50 por ciento. Para los jubilados y pensionados, el pr\u00e9stamo pasar\u00e1 de 400 mil a 600 mil pesos. Ambos tr\u00e1mites se podr\u00e1n hacer a partir del lunes 6 de noviembre: los trabajadores lo har\u00e1n virtualmente desde el sitio de ANSES, pero les enviaremos el c\u00f3digo para pasar por la oficina sin turno previo y los jubilados, como vienen haciendo hasta ahora, ir\u00e1n a la oficina con turno previo\u201d.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"font-size:24px\"><strong>Cr\u00e9ditos ANSES para trabajadores<\/strong><\/h2>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Los trabajadores en relaci\u00f3n de dependencia con salarios de hasta&nbsp;<strong>$1.980.000<\/strong>&nbsp;(piso del Impuesto a las Ganancias que rige desde hoy) podr\u00e1n pedir su pr\u00e9stamo de hasta&nbsp;<strong>$1 mill\u00f3n,<\/strong>&nbsp;con una&nbsp;<strong>Tasa Nominal Anual (TNA)<\/strong>&nbsp;del&nbsp;<strong>50%, en 24, 36 o 48 cuotas,<\/strong>&nbsp;cuyo monto se depositar\u00e1 en la&nbsp;<strong>tarjeta de cr\u00e9dito&nbsp;<\/strong>asociada a la cuenta sueldo del solicitante. La primera cuota&nbsp;<strong>se descontar\u00e1 a los 3 meses de recibido el pr\u00e9stamo.<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Esto implica un&nbsp;<strong>incremento del 150%<\/strong>&nbsp;del monto m\u00e1ximo actual ($400.000) y se estima que podr\u00eda&nbsp;<strong>alcanzar a m\u00e1s de 5,4 millones de personas que cumplir\u00edan con los requisitos.<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">La medida tiene por objetivo fomentar el consumo. Asimismo, busca ser una herramienta para aliviar la situaci\u00f3n de endeudamiento que atraviesan muchas familias trabajadoras, quienes tienen comprometido el pago de sus tarjetas de cr\u00e9dito con tasas de refinanciaci\u00f3n que son mucho m\u00e1s costosas que el cr\u00e9dito al que pueden acceder a trav\u00e9s de ANSES.<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Al momento, el organismo previsional ya otorg\u00f3 247.798 cr\u00e9ditos, el 38 por ciento a mujeres y el 62, a varones. Cabe recordar que la solicitud debe realizarse exclusivamente a trav\u00e9s de la web del organismo, www.anses.gob.ar, o de la aplicaci\u00f3n mi ANSES, todos los d\u00edas de 10 a 20 horas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:24px\"><strong>Cr\u00e9ditos para jubilados y pensionados<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Los jubilados y pensionados del Sistema Integrado Previsional Argentino (SIPA) podr\u00e1n acceder a pr\u00e9stamos de hasta 600 mil pesos y los titulares de Pensiones No Contributivas (PNC) y PUAM, de hasta 250 mil pesos, con una TNA del 29 por ciento, que significa un tercio de la que se ofrece en el mercado, y optar por devolverlo en hasta 24, 36 o 48 cuotas.<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Est\u00e1n en condiciones de solicitarlos la totalidad de los jubilados y pensionados, es decir, 7,7 millones de personas, fomentando el consumo en la econom\u00eda argentina. Al momento, ANSES entreg\u00f3 1.344.651 cr\u00e9ditos, el 64 por ciento a mujeres y el 36, a varones. Se recuerda que para obtener el pr\u00e9stamo se debe sacar turno en www.anses.gob.ar para, luego, tramitarse personalmente en las oficinas del organismo. En caso de cumplir con las condiciones, el dinero ser\u00e1 depositado en la cuenta en la que la persona cobre su prestaci\u00f3n previsional.<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Fuente : Diario \u00c1mbito-Medios digitales<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las l\u00edneas de cr\u00e9ditos ANSES pasan de $400.000 a $600.000 para jubilados y pensionados, y hasta $1 mill\u00f3n para trabajadores en relaci\u00f3n de dependencia. Ser\u00e1 desde el pr\u00f3ximo lunes 6 de noviembre. El ministro de Econom\u00eda y candidato a presidente,&nbsp;Sergio Massa,&nbsp;y la directora ejecutiva de ANSES,&nbsp;Fernanda Raverta,&nbsp;anunciaron este mi\u00e9rcoles un&nbsp;aumento en el monto que ofrecen [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2410,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[81,39],"tags":[231,66,149,357,40],"class_list":["post-2408","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","category-politica","tag-anses","tag-economia","tag-elecciones-2023","tag-plan-platita","tag-politica"],"blog_post_layout_featured_media_urls":{"thumbnail":["https:\/\/lavozdisruptiva.com\/wp-content\/uploads\/2023\/11\/Plan-platita-ANSES-150x150.webp",150,150,true],"full":["https:\/\/lavozdisruptiva.com\/wp-content\/uploads\/2023\/11\/Plan-platita-ANSES.webp",1200,900,false]},"categories_names":{"81":{"name":"Nacional","link":"https:\/\/lavozdisruptiva.com\/index.php\/category\/nacional\/"},"39":{"name":"Pol\u00edtica","link":"https:\/\/lavozdisruptiva.com\/index.php\/category\/politica\/"}},"tags_names":{"231":{"name":"ANSES","link":"https:\/\/lavozdisruptiva.com\/index.php\/tag\/anses\/"},"66":{"name":"Econom\u00eda","link":"https:\/\/lavozdisruptiva.com\/index.php\/tag\/economia\/"},"149":{"name":"Elecciones 2023","link":"https:\/\/lavozdisruptiva.com\/index.php\/tag\/elecciones-2023\/"},"357":{"name":"Plan platita","link":"https:\/\/lavozdisruptiva.com\/index.php\/tag\/plan-platita\/"},"40":{"name":"Pol\u00edtica","link":"https:\/\/lavozdisruptiva.com\/index.php\/tag\/politica\/"}},"comments_number":"0","wpmagazine_modules_lite_featured_media_urls":{"thumbnail":["https:\/\/lavozdisruptiva.com\/wp-content\/uploads\/2023\/11\/Plan-platita-ANSES-150x150.webp",150,150,true],"cvmm-medium":["https:\/\/lavozdisruptiva.com\/wp-content\/uploads\/2023\/11\/Plan-platita-ANSES-300x300.webp",300,300,true],"cvmm-medium-plus":["https:\/\/lavozdisruptiva.com\/wp-content\/uploads\/2023\/11\/Plan-platita-ANSES-305x207.webp",305,207,true],"cvmm-portrait":["https:\/\/lavozdisruptiva.com\/wp-content\/uploads\/2023\/11\/Plan-platita-ANSES-400x600.webp",400,600,true],"cvmm-medium-square":["https:\/\/lavozdisruptiva.com\/wp-content\/uploads\/2023\/11\/Plan-platita-ANSES-600x600.webp",600,600,true],"cvmm-large":["https:\/\/lavozdisruptiva.com\/wp-content\/uploads\/2023\/11\/Plan-platita-ANSES-1024x900.webp",1024,900,true],"cvmm-small":["https:\/\/lavozdisruptiva.com\/wp-content\/uploads\/2023\/11\/Plan-platita-ANSES-130x95.webp",130,95,true],"full":["https:\/\/lavozdisruptiva.com\/wp-content\/uploads\/2023\/11\/Plan-platita-ANSES.webp",1200,900,false]},"_links":{"self":[{"href":"https:\/\/lavozdisruptiva.com\/index.php\/wp-json\/wp\/v2\/posts\/2408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lavozdisruptiva.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lavozdisruptiva.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lavozdisruptiva.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lavozdisruptiva.com\/index.php\/wp-json\/wp\/v2\/comments?post=2408"}],"version-history":[{"count":3,"href":"https:\/\/lavozdisruptiva.com\/index.php\/wp-json\/wp\/v2\/posts\/2408\/revisions"}],"predecessor-version":[{"id":2429,"href":"https:\/\/lavozdisruptiva.com\/index.php\/wp-json\/wp\/v2\/posts\/2408\/revisions\/2429"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lavozdisruptiva.com\/index.php\/wp-json\/wp\/v2\/media\/2410"}],"wp:attachment":[{"href":"https:\/\/lavozdisruptiva.com\/index.php\/wp-json\/wp\/v2\/media?parent=2408"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lavozdisruptiva.com\/index.php\/wp-json\/wp\/v2\/categories?post=2408"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lavozdisruptiva.com\/index.php\/wp-json\/wp\/v2\/tags?post=2408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}